{"id":1212,"date":"2014-12-26T17:16:05","date_gmt":"2014-12-26T17:16:05","guid":{"rendered":"https:\/\/blogs.futura-sciences.com\/luminet\/?p=1212"},"modified":"2015-01-31T03:12:34","modified_gmt":"2015-01-31T03:12:34","slug":"zazie-dans-le-cosmos-24-oh-jeunesse","status":"publish","type":"post","link":"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/","title":{"rendered":"Zazie dans le Cosmos (2\/4) : Oh jeunesse"},"content":{"rendered":"<p>Suite du <strong><a title=\"Zazie dans le Cosmos (1\/4) : Lucr\u00e8ce au XXe si\u00e8cle\" href=\"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/16\/zazie-cosmos\/\" target=\"_blank\">billet pr\u00e9c\u00e9dent : Lucr\u00e8ce au XXe si\u00e8cle<\/a><\/strong><\/p>\n<p style=\"text-align: justify\">On ne peut pas lire la <em>Petite Cosmogonie Portative<\/em> sans se livrer \u00e0 une sorte de jeu savant. Au premier abord, le sens semble tr\u00e8s herm\u00e9tique, m\u00eame si l\u2019on est d\u2019embl\u00e9e saisi par le plaisir jubilatoire des jeux du langage. Les glissements de sens ne cessent de conduire du domaine scientifique au domaine profane et vice-versa, faisant de l\u2019\u00e9volution du monde un ph\u00e9nom\u00e8ne \u00e0 la fois formidable et trivial. Mais on a du mal \u00e0 comprendre ces vers qui abondent en m\u00e9taphores et \u00e9nigmes quasi impossibles \u00e0 d\u00e9chiffrer. Les tables synoptiques qui introduisent les six chants permettent toutefois d\u2019identifier, vers apr\u00e8s vers, les sujets trait\u00e9s et, par cons\u00e9quent, de d\u00e9coder m\u00eame les passages les plus ardus. Le texte est donc agr\u00e9ment\u00e9 d\u2019une v\u00e9ritable mode d\u2019emploi sous la forme d\u2019un syst\u00e8me de lecture contraignant qui fonctionne comme une clef d\u2019acc\u00e8s \u00e0 ses significations.<\/p>\n<p style=\"text-align: justify\">En participant \u00e0 ce jeu, le lecteur finit par d\u00e9couvrir que chaque m\u00e9taphore contient des informations d\u2019une justesse \u00e9tonnante, brouill\u00e9es par un r\u00e9seau de d\u00e9formations verbales et fantasmatiques produisant une syntaxe autre, g\u00e9n\u00e9ratrice de significations inattendues.<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/comestes-chute-2.jpg\" rel=\"lightbox[1212]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-1227\" src=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/comestes-chute-2-450x280.jpg\" alt=\"EPSON scanner Image\" width=\"249\" height=\"155\" srcset=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/comestes-chute-2-450x280.jpg 450w, https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/comestes-chute-2-1024x637.jpg 1024w, https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/comestes-chute-2.jpg 1771w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/a>Prenons quelques exemples dans le chant I, reproduit int\u00e9gralement en fin de ce billet (cadeau de No\u00ebl). <!--more-->La table synoptique indique clairement que l\u2019ouverture du po\u00e8me est consacr\u00e9e \u00e0 <a title=\"Arch\u00e9en\" href=\"http:\/\/fr.wikipedia.org\/wiki\/Arch%C3%A9en\" target=\"_blank\">l\u2019Arch\u00e9en<\/a>, l\u2019\u00e8re la plus ancienne de l\u2019histoire astronomique et g\u00e9ologique de notre plan\u00e8te\u00a0: il y a environ 4,6 milliards d\u2019ann\u00e9es, notre plan\u00e8te naissante \u00e9tait un globe incandescent recouvert par une \u00e9corce mince et instable constitu\u00e9e de laves et de tufs. Pour \u00e9voquer ces tumultes, Queneau puise son imagerie dans le registre physiologique\u00a0; nous d\u00e9couvrons alors le sens pr\u00e9cis des m\u00e9taphores telles \u00ab\u00a0le cul de s\u00e8che momie\u00a0\u00bb (r\u00e9tr\u00e9cissement par refroidissement de la cro\u00fbte terrestre, plissements cons\u00e9quents \u00e0 l\u2019activit\u00e9 tellurique), les \u00ab\u00a0varices \u00e9clat\u00e9es\u00a0\u00bb (activit\u00e9 tellurique) ou l\u2019image des alambics d\u2019une distillerie (\u00e9voquant la fusion partielle des roches). \u00c0 cette \u00e9poque les corps plan\u00e9taires vagabondaient dans le syst\u00e8me solaire en formation, les com\u00e8tes se d\u00e9versaient par vagues (Queneau \u00e9voque le passage de la com\u00e8te p\u00e9riodique de Halley en 1910) et s\u2019engloutissaient dans la mati\u00e8re bouillonnante de la terre, avant d\u2019\u00eatre liqu\u00e9fi\u00e9s par la chaleur intestine qui s\u00e9parait leurs constituants solides et gazeux :<\/p>\n<p style=\"text-align: justify\"><em>\u00f4 terre qui se prom\u00e8ne<\/em><br \/>\n<em>entre deux vagues de com\u00e8tes paraboles<\/em><br \/>\n<em>arbres des bustes noirs la com\u00e8te est ellipse<\/em><br \/>\n<em>arbres des lambris noirs elle va r\u00e9trograde<\/em><br \/>\n<em>la com\u00e8te inclin\u00e9e en mil neuf cent et dix<\/em><\/p>\n<table style=\"height: 283px\" width=\"485\">\n<tbody>\n<tr>\n<td style=\"text-align: justify\"><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1232\" src=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/atome-primitif-301x450.jpg\" alt=\"atome-primitif\" width=\"166\" height=\"248\" srcset=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/atome-primitif-301x450.jpg 301w, https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/atome-primitif.jpg 489w\" sizes=\"auto, (max-width: 166px) 100vw, 166px\" \/><\/em><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1201\" src=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/3-028hyper-320x450.jpg\" alt=\"3-028hyper\" width=\"178\" height=\"250\" srcset=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/3-028hyper-320x450.jpg 320w, https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/3-028hyper.jpg 427w\" sizes=\"auto, (max-width: 178px) 100vw, 178px\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\">Plus loin (vers 79-98), Queneau se r\u00e9f\u00e8re \u00e0 la <a title=\"atome primitif\" href=\"http:\/\/fr.wikipedia.org\/wiki\/Atome_primitif\" target=\"_blank\">th\u00e9orie de l\u2019atome primitif <\/a>expos\u00e9e par Georges Lema\u00eetre en 1931 et d\u00e9velopp\u00e9e par George Gamow en 1948, dans laquelle, en se fondant sur les \u00e9quations de la relativit\u00e9 d\u2019Einstein, la naissance de l\u2019Univers est d\u00e9crite comme une gigantesque explosion primordiale donnant naissance aux \u00e9l\u00e9ments (vers 135-157). On notera qu\u2019\u00e0 la date de composition du po\u00e8me, le mod\u00e8le de Lema\u00eetre (rebaptis\u00e9 plus tard big-bang) \u00e9tait loin d\u2019\u00eatre accept\u00e9 par la communaut\u00e9 scientifique. Le po\u00e8te fait d\u2019ailleurs allusion \u00e0 l\u2019expansion de l\u2019univers (\u00ab\u00a0Vives les n\u00e9buleuses\/ se trissaient en formant un espace au nez creux\u00a0\u00bb), l\u2019une des bases de la th\u00e9orie du big-bang. Bien plus \u00e9tonnant, on peut voir dans le distique \u00ab\u00a0hyper leur quatre trucs \u00e9clatement burlesque \/ atome insuffisant atome gigantesque\u00a0\u00bb l\u2019extraordinaire intuition d\u2019un mod\u00e8le que les physiciens th\u00e9oriciens ne d\u00e9velopperont que dans les ann\u00e9es 1980, \u00e0 savoir le brutal d\u00e9couplage d\u2019une \u00ab\u00a0hyperforce\u00a0\u00bb originelle en quatre interactions fondamentales \u2013 gravitation, \u00e9lectromagn\u00e9tisme, interactions nucl\u00e9aires forte et faible \u2013 qui gouvernent l\u2019ensemble des processus physiques connus.<\/p>\n<figure id=\"attachment_1229\" aria-describedby=\"caption-attachment-1229\" style=\"width: 428px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/smbrk.gif\" rel=\"lightbox[1212]\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1229\" src=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/smbrk.gif\" alt=\"Le d\u00e9couplage de &quot;l'hyperforce&quot; unitaire en quatre interactions fondamentales selon le mod\u00e8le du big bang \" width=\"428\" height=\"362\" \/><\/a><figcaption id=\"caption-attachment-1229\" class=\"wp-caption-text\">Le d\u00e9couplage de &#8220;l&#8217;hyperforce&#8221; originelle en quatre interactions fondamentales selon le mod\u00e8le du big bang<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Queneau donne ensuite (v. 158-188) une description du Syst\u00e8me solaire en utilisant les mythes gr\u00e9co-latins \u2013 cens\u00e9s \u00eatre familiers de tous \u2013 comme intercesseurs entre le po\u00e8te et le public. Il joue par exemple sur l\u2019ambivalence entre Mercure, le dieu romain, et mercure, l\u2019\u00e9l\u00e9ment chimique\u00a0; il joue surtout sur le nom des plan\u00e8tes et les attributs du dieu qu\u2019elles repr\u00e9sentent : \u00ab le commer\u00e7ant (Mercure) peut r\u00eaver la putain (V\u00e9nus) dormir\/ le colonel (Mars, dieu de la guerre) fumer du tabac caporal\/ le fonctionnaire baille (Jupiter) et le vieillard somnole (Saturne) \/ ce f\u00e9roce p\u00e9d\u00e9 (Uranus) se calme le zizi\/ le marin tout au loin lugubre se d\u00e9sole \/de naviguer si pr\u00e8s du bout de l\u2019infini (Neptune)\/ car il ne conna\u00eet pas le mineur endurci (Pluton) \u00bb[1].<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/systsol.gif\" rel=\"lightbox[1212]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1238\" src=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/systsol-450x199.gif\" alt=\"systsol\" width=\"450\" height=\"199\" srcset=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/systsol-450x199.gif 450w, https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/systsol-1024x453.gif 1024w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p style=\"text-align: justify\">Enfin, fascin\u00e9 par l\u2019\u00e9volution biologique, le po\u00e8te d\u00e9crit le passage des cristaux aux virus (vers 214-224). Les cristaux montrent le fascinant spectacle d\u2019un processus d\u2019organisation qui appara\u00eet dans le chaos mol\u00e9culaire et qui rev\u00eat une r\u00e9gularit\u00e9 p\u00e9riodique. Queneau les \u00e9voque par les m\u00e9taphores de savants rigoureux et des horlogers. Bien qu\u2019ils appartiennent au r\u00e8gne min\u00e9ral, les cristaux s\u2019apparentent aux organismes vivants, car ils n\u00e9cessitent d\u2019une part des conditions de pression et de temp\u00e9rature favorables pour pouvoir na\u00eetre et cro\u00eetre, d\u2019autre part ils ont un mode de croissance sp\u00e9cifique. \u00c0 partir de la propri\u00e9t\u00e9 des cristaux de reproduire leur ordre g\u00e9om\u00e9trique par un processus semblable \u00e0 celui de la f\u00e9condation, les biochimistes et les astronomes ont formul\u00e9 l\u2019hypoth\u00e8se d\u2019une \u00e9volution chimique de la mati\u00e8re min\u00e9rale, qui serait \u00e0 l\u2019origine des mol\u00e9cules organiques dont se composent tous les organismes vivants.<\/p>\n<p style=\"text-align: justify\">\u00c0 l\u2019\u00e9poque o\u00f9 Queneau a \u00e9crit son texte, cette hypoth\u00e8se attirait l\u2019attention des chercheurs. Les biochimistes A. I. Oparine et J. B. S. Haldane avaient envisag\u00e9 que le m\u00e9lange d\u2019hydrog\u00e8ne, m\u00e9thane, ammoniac et vapeur d\u2019eau qui composait l\u2019atmosph\u00e8re primitive de la terre, soumis \u00e0 l\u2019action du rayonnement solaire (rayons X et ultraviolets), aurait pu engendrer des mol\u00e9cules organiques\u00a0; tomb\u00e9es dans les oc\u00e9ans, elles auraient form\u00e9 la \u00ab\u00a0soupe chaude primitive\u00a0\u00bb o\u00f9 seraient n\u00e9es, par fermentation et synth\u00e8se photochimique, les premi\u00e8res bact\u00e9ries. Les premiers essais exp\u00e9rimentaux furent l\u2019\u0153uvre du chercheur am\u00e9ricain Stanley Miller et datent de 1953. Queneau devait consid\u00e9rer cette th\u00e9orie comme tr\u00e8s prometteuse, \u00e9tant donn\u00e9e l\u2019exactitude avec laquelle il \u00e9voque le passage du min\u00e9ral au vivant. <a href=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/Urey-Miller-experiment.jpg\" rel=\"lightbox[1212]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1242\" src=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/Urey-Miller-experiment-450x337.jpg\" alt=\"Urey-Miller-experiment\" width=\"450\" height=\"337\" srcset=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/Urey-Miller-experiment-450x337.jpg 450w, https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/Urey-Miller-experiment.jpg 800w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p>[1] Queneau intercale entre Mars et Jupiter le vers \u00ab\u00a0des gamins divaguer en un jeu machinal\u00a0\u00bb pour d\u00e9crire la ceinture d\u2019ast\u00e9ro\u00efdes gravitant entre ces deux plan\u00e8tes, inconnue dans l\u2019antiquit\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>PETITE COSMOGONE PORTATIVE (EXTRAIT\u00a0: CHANT I)<\/strong><\/p>\n<address><em>Naissance et jeunesse de la Terre. Elle mugit et enfante (1-45). La lune se d\u00e9tache d\u2019elle (46-64). Volcans et s\u00e9diments (arbres et d\u00e9luges) (64-79). Retour sur les origines\u00a0: l&#8217;atome primitif, l&#8217;\u00e2ge du monde, la n\u00e9buleuse primordiale (79-98). Les nombres (98-134). L&#8217;\u00e9clatement de l&#8217;atome primitif donne naissance \u00e0 la vari\u00e9t\u00e9 des choses repr\u00e9sent\u00e9e par l&#8217;arc-en-ciel (135-157). Le soleil (158-169). Le syst\u00e8me solaire et la ronde des plan\u00e8tes (169-179), Mercure et V\u00e9nus (180), Mars (181), les ast\u00e9ro\u00efdes (182), Jupiter et Saturne (183), Uranus (184), Neptune (185-187), Pluton (187-188). \u00ab\u00a0 Le silence \u00e9ternel de ces espaces infinis&#8230;\u00a0\u00bb (189-193). L\u2019Oc\u00e9an Primaire et la naissance de la vie (194-213). Le passage des cristaux aux virus (214-224). La terre a enfant\u00e9 (224-226)<\/em><\/address>\n<p><strong>(1)<\/strong> La terre appara\u00eet p\u00e2le et blette elle mugit<br \/>\ndistillant les gruaux qui gloussent dans le tube<br \/>\no\u00f9 s\u2019aspirent les crus des cro\u00fbtes de la nuit<br \/>\ngouttes de la microbienne entr\u00e9e au sourd puits<br \/>\nla terre appara\u00eet p\u00e2le et blette elle s\u2019imbibe<br \/>\nde la sueur que vomit la fi\u00e8vre des orages<br \/>\nUn calme s\u2019\u00e9tablit Les nuages ont fondu<br \/>\ncomme le plomb balourd des soldats surv\u00e9cus<br \/>\nUn lierre un gard\u00e9nia des fleurs enfantillages<br \/>\naccomplissent le joug des temps m\u00fbrs sur la terre<br \/>\nC\u2019est encor des vaccins et c\u2019est encor des nuages<br \/>\nla piq\u00fbre d\u2019\u00e9clair dans la cuisse des sols<br \/>\net l\u2019odeur de l\u2019\u00e9ther dans l\u2019op\u00e9ration g\u00e9e<br \/>\net le taire du ciel modelant les montagnes<br \/>\net le traire des monts la lave et l\u2019archipel<br \/>\nla terre terrassant d\u00e9mente se d\u00e9m\u00e8ne<br \/>\net se plisse comme un cul de s\u00e8che momie<br \/>\n\u00e9talant ses varices \u00e9clat\u00e9es Jeunesse<br \/>\njeunesse \u00f4 jeunesse \u00f4 terre qui se prom\u00e8ne<br \/>\nentre deux vagues de com\u00e8tes paraboles<br \/>\narbres des bustes noirs la com\u00e8te est ellipse<br \/>\narbres des lambris noirs elle va r\u00e9trograde<br \/>\nla com\u00e8te inclin\u00e9e en mil neuf cent et dix<br \/>\narbres des cercles noirs arbres des piliers noirs<br \/>\n\u00f4 jeunesse \u00f4 jeunesse et cette terre qui<br \/>\nse contracte exalt\u00e9e en sa m\u00fbre besogne<br \/>\narbres qui sur la blette terre qui mugit<br \/>\nles arbres ont pondu des ravins de cigognes<br \/>\nhannetons en rafale et scarab\u00e9es gigognes<br \/>\nles arbres ont meurtri leurs fentes crevass\u00e9es<br \/>\nd\u2019accouchements \u00e9pais et plut\u00f4t vivipares<br \/>\nun train qui b\u00ealait mou s\u2019affirme vieux zoaire<br \/>\net les barques coulant se veulent infusoires<br \/>\nla vie et puis la vie et puis de maints espoirs<br \/>\nle noyau qui se fisse et fendu comme fesse<br \/>\nalt\u00e8re une autre noix o\u00f9 les fils filiformes<br \/>\ng\u00eanent de leurs n\u00e9ants les possibles qui dorment<br \/>\ncoquillages d\u2019ivoire enveloppes de corne<br \/>\nles roues tournent galas dans le palais des spores<br \/>\nalgues et champignons bouillant dans la marmite<br \/>\nc\u2019est le seuil des sulfurs le d\u00e9clin des bromates<br \/>\nun gramme de silice perverse albumine<br \/>\nles chlorures les chaux d\u00e9gustent les virus<br \/>\ntrop grosses les cuillers ont vers\u00e9 laborantes<br \/>\ndes masses de liaisons qui d\u00e9j\u00e0 s\u2019adultinent<br \/>\n<strong>(46)<\/strong> Un gros moellon s\u2019en va salut lune salut<br \/>\njeunesse \u00f4 jeunesse \u00f4 des lundis arrach\u00e9e<br \/>\nles champs du Pacifique \u00e9coutaient ta mar\u00e9e<br \/>\nsalut lune salut lunaire est cet ab\u00eeme<br \/>\nun grand trou dans la terre et voici les eaux noires<br \/>\nsalut lune salut comm\u00e8re des histoires<br \/>\ndes \u00eatres qui cherchaient la d\u00e9route des monstres<br \/>\nse jetaient dans la plaie et vivaient inconnus<br \/>\net toi caillou volais bourrel\u00e9 de l\u00e9gendes<br \/>\nface de lampadaire et visage de brie<br \/>\nreine jaune ou blanch\u00e2tre et fusion de la nuit<br \/>\npoint n\u2019est besoin pour toi S\u00e9l\u00e9n\u00e9 de partir<br \/>\nde ce creux qu\u2019aussi bien peut former la d\u00e9rive<br \/>\nnoir est le jour la nuit noir est l\u2019arbre l\u2019atome<br \/>\nclaire saison des jours claire saison des nuits<br \/>\nbu\u00e9e au-dessus des eaux bu\u00e9e au-dessus des lunes<br \/>\nque valve toute lave en la porosit\u00e9<br \/>\nque la mer se foudroie en la pluie et puis qu\u2019une<br \/>\npluie am\u00e8ne la mer au-dessus de tout mont<br \/>\nla terre est revenue avec ce profil blet<br \/>\net ce nez avachi qu\u2019emporta satellite<br \/>\nle lourd support crat\u00e8re o\u00f9 g\u00e8le tout espace<br \/>\ncette \u00e9rotique acn\u00e9 qui module la face<br \/>\ndes m\u00e2les ing\u00e9nus des premi\u00e8res esp\u00e8ces<br \/>\net la terre plissait le s\u00e9diment des mers<br \/>\nbourgeonnait soupirait haletait ahanait<br \/>\nboutonnait pleurnichait ahanait haletait<br \/>\ngerminait haletait ahanait grommelait<br \/>\ndrageonnait ahanait haletait grognonnait<br \/>\npustulait boursouflait suppurait purulait<br \/>\nvolcans de tout anus laves de ce sphincter<br \/>\nla terre avait conchi\u00e9 l\u2019espace hym\u00e9noderme<br \/>\nla terre se voyait jeunesse en ces volumes<br \/>\n<strong>(79)<\/strong> hyper leur quatre trucs \u00e9clatement burlesque<br \/>\natome insuffisant atome gigantesque<br \/>\nrien \u00e0 rien suffisant tout au tout romanesque<br \/>\nle monde \u00e9tait moins vieux que les supputations<br \/>\net la terre moins gr\u00fb que quelque pute \u00e0 Sion<br \/>\nla terre \u00e9tait bien vierge et bien bouillonnaveuse<br \/>\nquelque constellation se penche un peu baveuse<br \/>\nsur des destins humains et des destins d&#8217;homards<br \/>\ntandis que le miel coule en la fesse argent\u00e9e<br \/>\ndes coquilles bleuies d&#8217;\u00e2ge en \u00e2ge hant\u00e9es<br \/>\npar un diog\u00e8ne ermite \u00e0 des noms raccord\u00e9s<br \/>\nbernard de tout succinct crabe de tout refus<br \/>\ntandis que le salp\u00eatre au fronti\u00e8re s&#8217;\u00e9loigne<br \/>\ndes sources de soleil tr\u00e8s indistinct t\u00e9moign-<br \/>\nage que des brouillons plus pr\u00e9cis \u00e9tal\u00e9s<br \/>\njeunesse oh jeunesse oh jeunesse n\u00e9buleuse<br \/>\nla terre t&#8217;a compt\u00e9e en tes \u00e9loignements<br \/>\net les muscles du sol se striaient savamment<br \/>\nen suivant la part fauve \u00e0 la course imp\u00e9rieuse<br \/>\n<strong>(98)<\/strong> r\u00e9serv\u00e9e en l&#8217;instant par un calcul d&#8217;alg\u00e8bre.<br \/>\nAutrefois les chiffres hame\u00e7ons de z\u00e9ros<br \/>\ninfiniment vari\u00e9s mijotaient en l&#8217;atome<br \/>\nind\u00e9finiment nus ind\u00e9finiment sots<br \/>\nmais leur compte \u00e9tait bon et les voici vaillants<br \/>\nchevauchant l&#8217;explosion oh jeunesse oh jeunesse<br \/>\nque le graphe \u00e9tait beau sillon d&#8217;entre tes fesses<br \/>\nn\u00e9buleuse obstin\u00e9e en ton \u00e9clatement<br \/>\njaillissant d&#8217;un point cru du zest de tous les mondes<br \/>\nencore in\u00e9pluch\u00e9s encore tout enfants<br \/>\net les ombres bagarraient en leur solitude<br \/>\net les voici vainqueurs chevauchant l&#8217;amplitude<br \/>\nde l&#8217;abc\u00e8s poin\u00e7onn\u00e9 du germe jaillissant<br \/>\nde la cro\u00fbte disloque et du feu magistral<br \/>\nde la pustule expue et du grain vertical<br \/>\net les voici connards en leur satisfaction<br \/>\nde se joindre couillards en leurs additions<br \/>\nde se retirer cons en leurs soustractions<br \/>\net de se reproduire en multiplications<br \/>\net de bien s&#8217;effondrer en toute division<br \/>\nde grandir \u00e0 fond dtrain en exponentiation<br \/>\net de se lambiner en simples logarithmes<br \/>\njeunesse oh jeunesse oh quand un chatouillait deux<br \/>\nsans savoir que son foutre en extrairait le tiers<br \/>\nquand les signes d&#8217;alg\u00e8bre amollissaient leurs jeux<br \/>\nquand les \u00e9galit\u00e9s reposaient dans le foie<br \/>\nalors analcoolique en l&#8217;atome adipeux<br \/>\net que l&#8217;informe quatt ptit spermatozo\u00efde<br \/>\nattendait de jouxter l&#8217;ovule arithmo\u00efde<br \/>\nquand le pus des erreurs ne d\u00e9goulinait pas<br \/>\nde la preuve par neuf ou de l&#8217;orgueil comptable<br \/>\noh jeunesse oh jeunesse alors \u00e0 cette table<br \/>\no\u00f9 le n\u00e9ant bouffait le d\u00e9jeuner instable<br \/>\ndes possibles conflits en une identit\u00e9<br \/>\nsurvint la loi tranchante et ind\u00e9composable<br \/>\nqui lan\u00e7a des trous d&#8217;\u00eatre en l&#8217;ind\u00e9finit\u00e9.<br \/>\nPetit arbre veineux petit bleu coquillage<br \/>\n<strong>(135)<\/strong> on ne sait d&#8217;o\u00f9 tu viens Les \u00e9toiles galopent<br \/>\nDes mondes l&#8217;entre deux s&#8217;\u00e9tale en une plage<br \/>\ndont on compte les voix tout comme en un gallup<br \/>\npetit vert autobus petit rouge meurtri<br \/>\npetit indigo bleu petit vert orang\u00e9<br \/>\npetite roue \u00e0 crans petite jambe \u00e0 jante<br \/>\npetit spectre d&#8217;azur petit mont de granit<br \/>\npetit orage m\u00fbr petite \u00e8re indulgente<br \/>\nun pin\u00e7on hors du temps a largement suffi<br \/>\npour d\u00e9clencher votre heure \u00e0 l&#8217;horloge offensante<br \/>\no\u00f9 l&#8217;espace au nez creux insolemment s&#8217;inscrit<br \/>\nLa terre se formait Vives les n\u00e9buleuses<br \/>\nse trissaient en formant un espace au nez creux<br \/>\npour que la terre y f\u00eet son nid o\u00f9 l&#8217;arbre bleu<br \/>\nle veineux coquillage et le rouge autobus<br \/>\net tous les vers meurtris toutes les roues \u00e0 jantes<br \/>\net les jambes \u00e0 cran et les monts de granit<br \/>\ns&#8217;y forassent leur trou s&#8217;y fondissent eux-m\u00eames<br \/>\noh jeunesse oh jeunesse oh ce soleil voil\u00e9<br \/>\ndu viol de l&#8217;indigo des volets du violet<br \/>\net des pleins de l&#8217;azur et des touches de rouge<br \/>\net des chaleurs du jaune oh lumi\u00e8re oh jeunesse<br \/>\n<strong>(158)<\/strong> oh soleil il se hisse imbib\u00e9 de fardauds<br \/>\ndes fardauds chauds d&#8217;un astre en loi d&#8217;\u00e9volution<br \/>\nil se hisse au-dessus de la ligne d&#8217;horizon<br \/>\ndes jours majestueux des jours d\u00e9goulinant<br \/>\nles jours d\u00e9goulinaient le long de sa face orbe<br \/>\ndans la nuit ils coulaient La phosphoreuse morve<br \/>\nde leurs jets indistincts adulait le soleil<br \/>\nquand la terre h\u00e9sitait \u00e0 sortir du sommeil<br \/>\ndu possible oh jeunesse oh jeunesse<br \/>\nsoleil couperos\u00e9 chevelu tachet\u00e9<br \/>\nsem\u00e9 de grains de son roux glaiseux jeune et sot<br \/>\n<strong>(169)<\/strong> p\u00e8re tr\u00e8s mod\u00e9r\u00e9 d&#8217;une tribu docile<br \/>\nils cyclent consciencieux toupies acrobatiques<br \/>\nchampions s\u00e9lectionn\u00e9s zigzaguant dans le ciel<br \/>\nleurs boucles pour un autre ont gueule d&#8217;astragale<br \/>\ncar leur sport d\u00e9confit leur mouvement spirale<br \/>\nmais les malins ont vu l&#8217;astuce plan\u00e9taire<br \/>\net leurs paris sont bons ils reviennent \u00e0 l&#8217;heure<br \/>\n\u00e0 la minute \u00e0 la seconde au si\u00e8cle au jour<br \/>\nles coureurs obstin\u00e9s dans la froideur des jours<br \/>\nla roulette est vaincue et le banquier fort riche<br \/>\nne cesse de payer sans deviner qu&#8217;on triche<br \/>\n<strong>(180)<\/strong> le commer\u00e7ant peut r\u00eaver la putain dormir<br \/>\nle colonel fumer du tabac caporal<br \/>\ndes gamins divaguer en un jeu machinal<br \/>\nle fonctionnaire b\u00e2ille et le vieillard somnole<br \/>\nce f\u00e9roce p\u00e9d\u00e9 se calme le zizi<br \/>\nle marin tout au loin lugubre se d\u00e9sole<br \/>\nde naviguer si pr\u00e8s du bout de l&#8217;infini<br \/>\ncar il ne conna\u00eet pas le mineur endurci<br \/>\nqui fonce aveugl\u00e9ment dans la fosse des nuits<br \/>\n<strong>(189)<\/strong> l&#8217;ivresse basculante et la vue \u00e9tourdie<br \/>\nils fr\u00e9quentent les ponts dans leurs carrosses bl\u00eames<br \/>\nperdant toujours leurs roues au coin du pont sur Seine<br \/>\nfroids navets p\u00e2les plan\u00e8tes boules b\u00e9molles<br \/>\ncheminant compagnons de la terre agricole<br \/>\n<strong>(194)<\/strong> jeunesse \u00f4 jeunesse \u00f4 terre encore ignicole<br \/>\ndont les plis se chargeaient de volcans ulc\u00e9r\u00e9s<br \/>\net les rides crevant de l\u2019un \u00e0 l\u2019autre p\u00f4le<br \/>\npropageaient les phlegmons des laves mijot\u00e9es<br \/>\nQuel bouillon de culture un oc\u00e9an primaire<br \/>\nquelle lavasse piante il para\u00eet surchauff\u00e9e<br \/>\nla ti\u00e9dasse bouillie en virus concoct\u00e9e<br \/>\nen vir et contre tus l\u2019oc\u00e9an accouchait<br \/>\nde merveilles de monts et d\u2019algues diatom\u00e9es<br \/>\nde grains albumineux de spores de pleine eau<br \/>\nboiteuses bact\u00e9ries rotif\u00e8res grumeaux<br \/>\npoivres g\u00e9latineux glaviots \u00e0 l\u2019air de morve<br \/>\nmilliasses de points vifs larmes \u00e0 l\u2019air de larve<br \/>\nfr\u00e9tillants bouscul\u00e9s de la neuve piscine<br \/>\no\u00f9 barbotait la terre \u00e9norme et enfantine<br \/>\nun peu blette pourtant d\u00e9j\u00e0 pomme praline<br \/>\npustulant du suc chaud de sa guerre intestine<br \/>\nnougat \u00e9bouillant\u00e9 flottant dans la vermine<br \/>\net bondissant parfois hors des eaux le dos fin<br \/>\nd\u2019une montagne claire \u00f4 jeunesse \u00f4 jeunesse<br \/>\n(214) les cristaux assembl\u00e9s se frottant leur carrure<br \/>\nfulgurent Les cristaux bourgeonnante nature<br \/>\ntravailleurs consciencieux savants nets stricts et purs<br \/>\nagitant leurs doigts fins savonnant leurs fissures<br \/>\nfulgurent Les cristaux laborieux horlogers<br \/>\nemprisonnant le temps dans leurs cribles filets<br \/>\net parfois saisissant l\u2019eau d\u2019une goutte molle<br \/>\nfulgurent Les cristaux f\u00e9condants ignicoles<br \/>\nsemant dans les matrices avides du sol<br \/>\njetant leur terme exact sur des ovaires vagues<br \/>\nfulgurent La terre accouche en hurlant et drague<br \/>\nle magma lumineux et la boueuse vie<br \/>\nla terre appara\u00eet p\u00e2le et blette Elle mugit<\/p>\n<p><a href=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/queneau_par_prassinos.jpg\" rel=\"lightbox[1212]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1221\" src=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/queneau_par_prassinos.jpg\" alt=\"queneau_par_prassinos\" width=\"275\" height=\"367\" \/><\/a><\/p>\n<p><a title=\"Zazie dans le cosmos (3\/4) : l\u2019ordre dans le chaos\" href=\"https:\/\/blogs.futura-sciences.com\/luminet\/2015\/01\/17\/zazie-dans-le-cosmos-34-lordre-dans-le-chaos\/\" target=\"_blank\"><strong><span style=\"color: #339966\">La suite est ici : L&#8217;ordre dans le\u00a0 chaos<\/span><\/strong><\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Suite du billet pr\u00e9c\u00e9dent : Lucr\u00e8ce au XXe si\u00e8cle On ne peut pas lire la Petite Cosmogonie Portative sans se livrer \u00e0 une sorte de jeu savant. Au premier abord, le sens semble tr\u00e8s herm\u00e9tique, m\u00eame si l\u2019on est d\u2019embl\u00e9e saisi par le plaisir jubilatoire des jeux du langage. Les glissements de sens ne cessent &hellip; <a href=\"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Zazie dans le Cosmos (2\/4) : Oh jeunesse<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":1230,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[14,5,46],"tags":[133,131,90,75],"class_list":["post-1212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire-des-sciences-sciences","category-litterature","category-poesie","tag-atome-primitif","tag-cosmogonie","tag-queneau","tag-systeme-solaire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zazie dans le Cosmos (2\/4) : Oh jeunesse, par Jean-Pierre Luminet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zazie dans le Cosmos (2\/4) : Oh jeunesse, par Jean-Pierre Luminet\" \/>\n<meta property=\"og:description\" content=\"Suite du billet pr\u00e9c\u00e9dent : Lucr\u00e8ce au XXe si\u00e8cle On ne peut pas lire la Petite Cosmogonie Portative sans se livrer \u00e0 une sorte de jeu savant. Au premier abord, le sens semble tr\u00e8s herm\u00e9tique, m\u00eame si l\u2019on est d\u2019embl\u00e9e saisi par le plaisir jubilatoire des jeux du langage. Les glissements de sens ne cessent &hellip; Continuer la lecture de Zazie dans le Cosmos (2\/4) : Oh jeunesse &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/\" \/>\n<meta property=\"og:site_name\" content=\"LUMINESCIENCES : le blog de Jean-Pierre LUMINET, astrophysicien\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-26T17:16:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-31T03:12:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/bigbang.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean-Pierre LUMINET\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean-Pierre LUMINET\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/\",\"url\":\"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/\",\"name\":\"Zazie dans le Cosmos (2\/4) : Oh jeunesse, par Jean-Pierre Luminet\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.futura-sciences.com\/luminet\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/bigbang.jpg\",\"datePublished\":\"2014-12-26T17:16:05+00:00\",\"dateModified\":\"2015-01-31T03:12:34+00:00\",\"author\":{\"@id\":\"https:\/\/blogs.futura-sciences.com\/luminet\/#\/schema\/person\/d61f577b54398f0ecee81e140e7643cb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/#primaryimage\",\"url\":\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/bigbang.jpg\",\"contentUrl\":\"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/bigbang.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Ce que n'est pas le Big Bang...\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogs.futura-sciences.com\/luminet\/#website\",\"url\":\"https:\/\/blogs.futura-sciences.com\/luminet\/\",\"name\":\"LUMINESCIENCES : le blog de Jean-Pierre LUMINET, astrophysicien\",\"description\":\"J\u2019eus le vertige et je pleurai car mes yeux avaient vu cet objet secret et conjectural dont les hommes usurpent le nom, mais qu\u2019aucun homme n\u2019a regard\u00e9 : l\u2019inconcevable univers.  Jorge Luis Borges, L\u2019Aleph (1949)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogs.futura-sciences.com\/luminet\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogs.futura-sciences.com\/luminet\/#\/schema\/person\/d61f577b54398f0ecee81e140e7643cb\",\"name\":\"Jean-Pierre LUMINET\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/blogs.futura-sciences.com\/luminet\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a6d27645b8081b2f766677414e6a83e1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a6d27645b8081b2f766677414e6a83e1?s=96&d=mm&r=g\",\"caption\":\"Jean-Pierre LUMINET\"},\"url\":\"https:\/\/blogs.futura-sciences.com\/luminet\/author\/jpluminet\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zazie dans le Cosmos (2\/4) : Oh jeunesse, par Jean-Pierre Luminet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/","og_locale":"fr_FR","og_type":"article","og_title":"Zazie dans le Cosmos (2\/4) : Oh jeunesse, par Jean-Pierre Luminet","og_description":"Suite du billet pr\u00e9c\u00e9dent : Lucr\u00e8ce au XXe si\u00e8cle On ne peut pas lire la Petite Cosmogonie Portative sans se livrer \u00e0 une sorte de jeu savant. Au premier abord, le sens semble tr\u00e8s herm\u00e9tique, m\u00eame si l\u2019on est d\u2019embl\u00e9e saisi par le plaisir jubilatoire des jeux du langage. Les glissements de sens ne cessent &hellip; Continuer la lecture de Zazie dans le Cosmos (2\/4) : Oh jeunesse &rarr;","og_url":"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/","og_site_name":"LUMINESCIENCES : le blog de Jean-Pierre LUMINET, astrophysicien","article_published_time":"2014-12-26T17:16:05+00:00","article_modified_time":"2015-01-31T03:12:34+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/bigbang.jpg","type":"image\/jpeg"}],"author":"Jean-Pierre LUMINET","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jean-Pierre LUMINET","Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/","url":"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/","name":"Zazie dans le Cosmos (2\/4) : Oh jeunesse, par Jean-Pierre Luminet","isPartOf":{"@id":"https:\/\/blogs.futura-sciences.com\/luminet\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/#primaryimage"},"image":{"@id":"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/bigbang.jpg","datePublished":"2014-12-26T17:16:05+00:00","dateModified":"2015-01-31T03:12:34+00:00","author":{"@id":"https:\/\/blogs.futura-sciences.com\/luminet\/#\/schema\/person\/d61f577b54398f0ecee81e140e7643cb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blogs.futura-sciences.com\/luminet\/2014\/12\/26\/zazie-dans-le-cosmos-24-oh-jeunesse\/#primaryimage","url":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/bigbang.jpg","contentUrl":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-content\/uploads\/sites\/2\/2014\/12\/bigbang.jpg","width":1920,"height":1080,"caption":"Ce que n'est pas le Big Bang..."},{"@type":"WebSite","@id":"https:\/\/blogs.futura-sciences.com\/luminet\/#website","url":"https:\/\/blogs.futura-sciences.com\/luminet\/","name":"LUMINESCIENCES : le blog de Jean-Pierre LUMINET, astrophysicien","description":"J\u2019eus le vertige et je pleurai car mes yeux avaient vu cet objet secret et conjectural dont les hommes usurpent le nom, mais qu\u2019aucun homme n\u2019a regard\u00e9 : l\u2019inconcevable univers.  Jorge Luis Borges, L\u2019Aleph (1949)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.futura-sciences.com\/luminet\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/blogs.futura-sciences.com\/luminet\/#\/schema\/person\/d61f577b54398f0ecee81e140e7643cb","name":"Jean-Pierre LUMINET","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blogs.futura-sciences.com\/luminet\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a6d27645b8081b2f766677414e6a83e1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6d27645b8081b2f766677414e6a83e1?s=96&d=mm&r=g","caption":"Jean-Pierre LUMINET"},"url":"https:\/\/blogs.futura-sciences.com\/luminet\/author\/jpluminet\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-json\/wp\/v2\/posts\/1212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-json\/wp\/v2\/comments?post=1212"}],"version-history":[{"count":17,"href":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-json\/wp\/v2\/posts\/1212\/revisions"}],"predecessor-version":[{"id":1311,"href":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-json\/wp\/v2\/posts\/1212\/revisions\/1311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-json\/wp\/v2\/media\/1230"}],"wp:attachment":[{"href":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-json\/wp\/v2\/media?parent=1212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-json\/wp\/v2\/categories?post=1212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.futura-sciences.com\/luminet\/wp-json\/wp\/v2\/tags?post=1212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}